{"id":14468,"date":"2023-08-16T22:34:31","date_gmt":"2023-08-16T22:34:31","guid":{"rendered":"https:\/\/lojadamente.com\/?post_type=product&#038;p=14468"},"modified":"2023-08-17T00:33:15","modified_gmt":"2023-08-17T00:33:15","slug":"detonando-o-ciume","status":"publish","type":"product","link":"https:\/\/chrisallmeida.com\/loja\/products\/detonando-o-ciume\/","title":{"rendered":"Detonando o Ci\u00fame"},"content":{"rendered":"<p>Seu relacionamento pode estar sendo destru\u00eddo por causa do ci\u00fame.<br \/>\nCi\u00fame \u00e9 a emo\u00e7\u00e3o usada pelo seu psiquismo como rea\u00e7\u00e3o ao medo de perder. Se voc\u00ea sofre descontroladamente com o ci\u00fame, sua autoestima cai, sua estabilidade fica abalada e o seu senso de dignidade vai por \u00e1gua abaixo\u2026<\/p>\n<h3><strong>Enfim, uma solu\u00e7\u00e3o definitiva e duradoura para o problema do ci\u00fame.<\/strong><\/h3>\n<p>Com a Reprograma\u00e7\u00e3o Mental \u201cDetonando o Ci\u00fame\u201d voc\u00ea reconquistar\u00e1 seu controle emocional e sua autoconfian\u00e7a. Ter\u00e1 melhores condi\u00e7\u00f5es de viver harmoniosamente o relacionamento afetivo\/amoroso com seu parceiro.<\/p>\n<p>Ao longo dos anos em minha atua\u00e7\u00e3o como psicoterapeuta vi muitos namoros e casamentos serem destru\u00eddos por causa do ci\u00fame. As pessoas perdem a cabe\u00e7a por nada e colocam tudo a perder.<\/p>\n<p>Sei que o ci\u00fame est\u00e1 intimamente ligado com suas inseguran\u00e7as internas e isto agora pode ser mudado. Desenvolvi a Reprograma\u00e7\u00e3o Mental \u201cDetonando o Ci\u00fame\u201d para que voc\u00ea possa viver a sua rela\u00e7\u00e3o com seguran\u00e7a e harmonia. Voc\u00ea receber\u00e1 um \u00e1udio em formato MP3 para ouvir todos os dias, por um certo per\u00edodo de tempo. Com isto, seus padr\u00f5es mentais negativos ser\u00e3o gradualmente alterados e melhorados.<\/p>\n<p>Voc\u00ea possui a capacidade de controlar os seus pr\u00f3prios pensamentos e eu vou te ensinar como fazer isto. Comandando de seu pr\u00f3prio pensar, voc\u00ea passar\u00e1 a escolher emo\u00e7\u00f5es mais positivas e ter\u00e1 como reescrever a sua hist\u00f3ria com a pessoa que ama.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ACESSO IMEDIATO!<\/strong><\/p>\n<p>Ap\u00f3s a confirma\u00e7\u00e3o do seu pagamento, voc\u00ea ter\u00e1 acesso a um \u00e1udio no formato de MP3 com 30 minutos de dura\u00e7\u00e3o. Poder\u00e1 ouvir no seu pr\u00f3prio computador ou baix\u00e1-lo para ouvir em qualquer aparelho que comporte a fun\u00e7\u00e3o de MP3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pare de sofrer e de ser torturado pelos pr\u00f3prios pensamentos.\u00a0 Recupere seu controle emocional. Eleve sua autoestima e autoconfian\u00e7a.<\/p>\n","protected":false},"featured_media":14471,"template":"","meta":[],"product_cat":[1524,1633,1688,1992],"product_tag":[1567,1571,1589,2115,2116,1786,1876,1973],"class_list":["post-14468","product","type-product","status-publish","has-post-thumbnail","product_cat-amor-relacionamentos","product_cat-comunicacao-verbal","product_cat-eliminando-fobias-traumas-vicios","product_cat-saude-bem-estar","product_tag-autoconfianca","product_tag-autoestima","product_tag-casamento","product_tag-ciume","product_tag-ciumes","product_tag-inseguranca","product_tag-namoro","product_tag-relacionamentos","first","instock","sale","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product\/14468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media\/14471"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media?parent=14468"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_cat?post=14468"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_tag?post=14468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}