{"id":11525,"date":"2022-05-01T18:42:16","date_gmt":"2022-05-01T18:42:16","guid":{"rendered":"https:\/\/chrisallmeida.com\/?post_type=product&amp;p=11525"},"modified":"2022-05-01T18:42:16","modified_gmt":"2022-05-01T18:42:16","slug":"vicio-em-jogos-eletronicos","status":"publish","type":"product","link":"https:\/\/chrisallmeida.com\/loja\/products\/vicio-em-jogos-eletronicos\/","title":{"rendered":"V\u00edcio em Jogos Eletr\u00f4nicos"},"content":{"rendered":"<p>A classifica\u00e7\u00e3o do transtorno dos jogos eletr\u00f4nicos como uma doen\u00e7a pela OMS levanta o alerta sobre as consequ\u00eancias f\u00edsicas e emocionais do tempo excessivo gasto em games,\u00a0n\u00e3o s\u00f3 entre os jovens, mas tamb\u00e9m entre adultos.<\/p>\n<p>Jogos de corrida, de cassino, de RPG ou meras pecinhas coloridas que se encaixam. N\u00e3o importa.\u00a0<strong>Nosso tempo \u00e9 valioso e limitado. Chega uma hora que \u00e9 preciso dizer N\u00c3O!<\/strong><\/p>\n<h3>Quanto tempo e energia n\u00e3o est\u00e1 sendo desperdi\u00e7ada em um ambiente virtual que n\u00e3o agrega absolutamente nada de concreto para sua vida real.<\/h3>\n<p>Por este motivo, desenvolvemos a reprograma\u00e7\u00e3o mental V\u00cdCIO EM JOGOS ELETR\u00d4NICOS. Uma \u00e1udio-hipnose com 30 minutos de dura\u00e7\u00e3o, gravada pelo Chris Allmeida<\/p>\n<p>&nbsp;<\/p>\n<p><strong>O QUE EXATAMENTE ESTOU ADQUIRINDO?<\/strong><\/p>\n<p>Ap\u00f3s a confirma\u00e7\u00e3o do pagamento voc\u00ea receber\u00e1 um link para baixar seu\u00a0<strong>arquivo em \u00e1udio, no formato MP3, com 30 minutos de dura\u00e7\u00e3o<\/strong>. Este \u00e1udio foi desenvolvido e gravado pelo Chris Allmeida.<\/p>\n<p>Poder\u00e1 ouvir este \u00e1udio onde desejar: No seu celular, computador, tablet ou qualquer aparelho que comporte a fun\u00e7\u00e3o MP3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A classifica\u00e7\u00e3o do transtorno dos jogos eletr\u00f4nicos como uma doen\u00e7a pela OMS levanta o alerta sobre as consequ\u00eancias f\u00edsicas e emocionais do tempo excessivo gasto em games,\u00a0n\u00e3o s\u00f3 entre os jovens, mas tamb\u00e9m entre adultos. Jogos de corrida, de cassino, de RPG ou meras pecinhas coloridas que se encaixam. N\u00e3o importa.\u00a0Nosso tempo \u00e9 valioso e [&hellip;]<\/p>\n","protected":false},"featured_media":11526,"template":"","meta":[],"product_cat":[1688,1992],"product_tag":[1590,1592,1631,1751,1752,1793,1794,1795,1796,1797,1798,1989,2071,2078],"class_list":["post-11525","product","type-product","status-publish","has-post-thumbnail","product_cat-eliminando-fobias-traumas-vicios","product_cat-saude-bem-estar","product_tag-cassino","product_tag-celular","product_tag-computador","product_tag-game","product_tag-games","product_tag-jogar-video-mage","product_tag-jogo","product_tag-jogos","product_tag-jogos-de-acao","product_tag-jogos-de-luta","product_tag-jogos-eletronicos","product_tag-rpg","product_tag-viciado","product_tag-video-game","first","instock","downloadable","virtual","sold-individually","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product\/11525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media\/11526"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media?parent=11525"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_cat?post=11525"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_tag?post=11525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}