{"id":11523,"date":"2022-05-01T18:39:11","date_gmt":"2022-05-01T18:39:11","guid":{"rendered":"https:\/\/chrisallmeida.com\/?post_type=product&amp;p=11523"},"modified":"2022-05-01T18:39:11","modified_gmt":"2022-05-01T18:39:11","slug":"ativacao-da-glandula-pineal","status":"publish","type":"product","link":"https:\/\/chrisallmeida.com\/loja\/products\/ativacao-da-glandula-pineal\/","title":{"rendered":"Ativa\u00e7\u00e3o da Gl\u00e2ndula Pineal"},"content":{"rendered":"<h2 class=\"has-text-align-center\">Uma T\u00e9cnica Simples e Pr\u00e1tica Para Melhorar Seu Sono, Reduzir Seu Apetite, Melhorar Seu Desempenho Sexual, Aumentar Sua Concentra\u00e7\u00e3o e Muito Mais!<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>O QUE \u00c9 A GL\u00c2NDULA PINEAL?<\/strong><\/p>\n<p>A gl\u00e2ndula pineal, \u00e9 uma pequena gl\u00e2ndula end\u00f3crina localizada na parte central do nosso c\u00e9rebro.\u00a0\u00c9 ela quem produz a melatonina, um horm\u00f4nio que cuida da qualidade de nosso sono e a serotonina, o horm\u00f4nio que estabelece a comunica\u00e7\u00e3o entre os neur\u00f4nios.<\/p>\n<p><iframe loading=\"lazy\" title=\"ATIVA&amp;Ccedil;&amp;Atilde;O DA GL&amp;Acirc;NDULA PINEAL\" src=\"https:\/\/player.vimeo.com\/video\/509030976?h=4bae0f5937&amp;dnt=1&amp;app_id=122963\" width=\"720\" height=\"480\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>A\u00a0<strong>melatonina<\/strong>\u00a0desempenha um papel muito importante no controle de nossas emo\u00e7\u00f5es.\u00a0O estresse, a ansiedade e at\u00e9 mesmo a depress\u00e3o e outras desordens mentais podem ser curados quando a produ\u00e7\u00e3o de melatonina se encontra em n\u00edveis adequados.\u00a0Al\u00e9m disso, a press\u00e3o sangu\u00ednea e a sa\u00fade do seu cora\u00e7\u00e3o tendem a melhorar. Seu sistema imunol\u00f3gico fica fortalecido<\/p>\n<p>J\u00e1 a\u00a0<strong>serotonina<\/strong>\u00a0ajuda no controle do seu humor e da sua disposi\u00e7\u00e3o f\u00edsica. Melhora o seu sono, seu apetite (ou seja, capacidade de controlar a fome), sua mem\u00f3ria e sua capacidade de concentra\u00e7\u00e3o para ler e estudar.\u00a0Contribui com seu sistema digestivo al\u00e9m de controlar a temperatura do seu organismo.<\/p>\n<p>Muitas correntes espirituais tamb\u00e9m consideram a gl\u00e2ndula pineal como um ponto de contato com o plano espiritual.\u00a0Aquilo que chamamos de\u00a0<strong>terceira vis\u00e3o<\/strong>, ou seja, a capacidade de perceber outros n\u00edveis de realidade, \u00e9 pois um atributo de uma gl\u00e2ndula pineal saud\u00e1vel e desenvolvida.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMO FUNCIONA ESTE TRABALHO?<\/strong><\/p>\n<p>Este \u00e1udio consiste numa reprograma\u00e7\u00e3o mental com sons e frequ\u00eancias espec\u00edficas que, de acordo com estudos na \u00e1rea, auxiliam na estimula\u00e7\u00e3o da gl\u00e2ndula pineal.\u00a0 Al\u00e9m disto, no mesmo \u00e1udio s\u00e3o inclu\u00eddas v\u00e1rias afirma\u00e7\u00f5es indutivas (auto-hipnose) com o objetivo de desenvolver as caracter\u00edsticas e atribui\u00e7\u00f5es de uma gl\u00e2ndula pineal ativa e saud\u00e1vel.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>O QUE EXATAMENTE ESTOU ADQUIRINDO?<\/strong><\/p>\n<p>Um arquivo em \u00e1udio, no formato MP3, desenvolvido e gravado pelo Chris Allmeida com dura\u00e7\u00e3o aproximada de 45 minutos.<br \/>\nAp\u00f3s a confirma\u00e7\u00e3o de pagamento voc\u00ea receber\u00e1 um link para baixar este arquivo em \u00e1udio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma T\u00e9cnica Simples e Pr\u00e1tica Para Melhorar Seu Sono, Reduzir Seu Apetite, Melhorar Seu Desempenho Sexual, Aumentar Sua Concentra\u00e7\u00e3o e Muito Mais! &nbsp; O QUE \u00c9 A GL\u00c2NDULA PINEAL? A gl\u00e2ndula pineal, \u00e9 uma pequena gl\u00e2ndula end\u00f3crina localizada na parte central do nosso c\u00e9rebro.\u00a0\u00c9 ela quem produz a melatonina, um horm\u00f4nio que cuida da qualidade [&hellip;]<\/p>\n","protected":false},"featured_media":11524,"template":"","meta":[],"product_cat":[1677,1710,1839,1992],"product_tag":[1600,1709,1756,1845,1914,2005,2044],"class_list":["post-11523","product","type-product","status-publish","has-post-thumbnail","product_cat-dinheiro-e-prosperidade","product_cat-espiritualidade","product_cat-meditacao-relax","product_cat-saude-bem-estar","product_tag-clarividencia","product_tag-espiritualidade","product_tag-glandula-pineal","product_tag-melatonina","product_tag-pes","product_tag-serotonina","product_tag-terceira-visao","first","instock","downloadable","virtual","sold-individually","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product\/11523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media\/11524"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media?parent=11523"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_cat?post=11523"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_tag?post=11523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}