{"id":11452,"date":"2022-04-21T18:39:15","date_gmt":"2022-04-21T18:39:15","guid":{"rendered":"https:\/\/chrisallmeida.com\/?post_type=product&amp;p=11452"},"modified":"2022-04-21T18:39:15","modified_gmt":"2022-04-21T18:39:15","slug":"silenciar-a-mente","status":"publish","type":"product","link":"https:\/\/chrisallmeida.com\/loja\/products\/silenciar-a-mente\/","title":{"rendered":"Silenciar a Mente"},"content":{"rendered":"<p>O objetivo deste \u00e1udio \u00e9 pacificar sua mente. Trazer uma atmosfera de harmonia, paz e serenidade, principalmente quando estamos atravessando momentos de provas e supera\u00e7\u00e3o.<\/p>\n<p>Ideal para voc\u00ea se encontra ansioso, tenso ou nervoso, mas deseja elevar os n\u00edveis da sua frequ\u00eancia mental e emocional.<\/p>\n<p>Produzido e gravado pelo Chris Allmeida<\/p>\n<p>Dura\u00e7\u00e3o: 30 minutos<\/p>\n<p>&nbsp;<\/p>\n<p><strong>O que exatamente estou adquirindo?<\/strong><\/p>\n<p>Um arquivo de \u00e1udio MP3, com 30 minutos de dura\u00e7\u00e3o, gravado pelo Chris Allmeida. Ap\u00f3s a confirma\u00e7\u00e3o de sua compra, voc\u00ea receber\u00e1 um link para baixar seu \u00e1udio. Poder\u00e1 ouvir em seu celular, computador ou qualquer outro aparelho que comporte a fun\u00e7\u00e3o MP3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O objetivo deste \u00e1udio \u00e9 pacificar sua mente. Trazer uma atmosfera de harmonia, paz e serenidade, principalmente quando estamos atravessando momentos de provas e supera\u00e7\u00e3o. Ideal para voc\u00ea se encontra ansioso, tenso ou nervoso, mas deseja elevar os n\u00edveis da sua frequ\u00eancia mental e emocional. Produzido e gravado pelo Chris Allmeida Dura\u00e7\u00e3o: 30 minutos &nbsp; [&hellip;]<\/p>\n","protected":false},"featured_media":11453,"template":"","meta":[],"product_cat":[1710,1839,1992],"product_tag":[1516,1517,1518,1533,1558,1577,1713,1759,1838,1852,1882,1903,1904,1975,1976,2002,2011,2021,2033],"class_list":["post-11452","product","type-product","status-publish","has-post-thumbnail","product_cat-espiritualidade","product_cat-meditacao-relax","product_cat-saude-bem-estar","product_tag-aliviar","product_tag-aliviar-o-estresse","product_tag-aliviar-stress","product_tag-ansiedade","product_tag-audio-para-relaxar","product_tag-calma","product_tag-estresse","product_tag-harmonia","product_tag-meditacao","product_tag-mente","product_tag-nervosismo","product_tag-paz","product_tag-paz-interior","product_tag-relaxamento","product_tag-relaxar","product_tag-serenidade","product_tag-silenciar-a-mente","product_tag-stress","product_tag-tensao","first","instock","downloadable","virtual","sold-individually","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product\/11452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media\/11453"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media?parent=11452"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_cat?post=11452"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_tag?post=11452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}