{"id":11439,"date":"2022-04-21T16:35:16","date_gmt":"2022-04-21T16:35:16","guid":{"rendered":"https:\/\/chrisallmeida.com\/?post_type=product&amp;p=11439"},"modified":"2022-04-21T16:35:16","modified_gmt":"2022-04-21T16:35:16","slug":"alimentacao-moderada","status":"publish","type":"product","link":"https:\/\/chrisallmeida.com\/loja\/products\/alimentacao-moderada\/","title":{"rendered":"Alimenta\u00e7\u00e3o Moderada"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Esta \u00e9 uma reprograma\u00e7\u00e3o mental de 30 minutos, produzida e gravada pelo Chris Allmeida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ouvindo diariamente este \u00e1udio voc\u00ea perceber\u00e1 uma natural redu\u00e7\u00e3o de sua ansiedade, avidez ou necessidade de comer muito ou repetidamente. Isto te ajudar\u00e1 a emagrecer e a ter mais sa\u00fade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Perceber\u00e1 que nos hor\u00e1rios das refei\u00e7\u00f5es, apenas uma por\u00e7\u00e3o em seu prato ser\u00e1 o suficiente, sem precisar repetir. Desenvolver\u00e1 uma saud\u00e1vel disposi\u00e7\u00e3o em praticar momentos programados de jejum.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E o mais importante:<br \/>\n<strong>A alimenta\u00e7\u00e3o deixar\u00e1 de ser uma compensa\u00e7\u00e3o para vazios ou conflitos emocionais<\/strong>, tornando-se apenas aquilo que \u00e9: uma forma de nutrir o seu corpo e preservar sua integridade.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>O que exatamente estou adquirindo?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Um arquivo em formato de \u00e1udio MP3 com 30 minutos de dura\u00e7\u00e3o gravado pelo Chris Almeida<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Como recebo este produto?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Este \u00e9 um produto digital. Ap\u00f3s a confirma\u00e7\u00e3o de sua compra voc\u00ea receber\u00e1 um link para baixar seu \u00e1udio. Poder\u00e1 ent\u00e3o ouvir em seu computador, smartphone, tablet ou qualquer outro aparelho que comporte a fun\u00e7\u00e3o de \u00e1udio MP3.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta \u00e9 uma reprograma\u00e7\u00e3o mental de 30 minutos, produzida e gravada pelo Chris Allmeida. Ouvindo diariamente este \u00e1udio voc\u00ea perceber\u00e1 uma natural redu\u00e7\u00e3o de sua ansiedade, avidez ou necessidade de comer muito ou repetidamente. Isto te ajudar\u00e1 a emagrecer e a ter mais sa\u00fade. Perceber\u00e1 que nos hor\u00e1rios das refei\u00e7\u00f5es, apenas uma por\u00e7\u00e3o em seu [&hellip;]<\/p>\n","protected":false},"featured_media":11440,"template":"","meta":[],"product_cat":[1992],"product_tag":[1515,1533,1609,1611,1675,1690,1692,1965],"class_list":["post-11439","product","type-product","status-publish","has-post-thumbnail","product_cat-saude-bem-estar","product_tag-alimentacao","product_tag-ansiedade","product_tag-comer-menos","product_tag-comida","product_tag-dieta","product_tag-emagrecer","product_tag-emagrecimento","product_tag-regime","first","instock","sale","downloadable","virtual","sold-individually","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product\/11439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media\/11440"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/media?parent=11439"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_cat?post=11439"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/loja\/wp-json\/wp\/v2\/product_tag?post=11439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}