{"id":5536,"date":"2011-08-14T05:00:37","date_gmt":"2011-08-14T08:00:37","guid":{"rendered":"https:\/\/chrisallmeida.com\/blog\/?p=768"},"modified":"2011-08-14T05:00:37","modified_gmt":"2011-08-14T08:00:37","slug":"prosperidade-por-onde-comecar","status":"publish","type":"post","link":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/","title":{"rendered":"Prosperidade &#8211; Por onde come\u00e7ar?"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/wpchrisallmeida.s3.amazonaws.com\/wp-content\/uploads\/2011\/08\/caminheiro.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-769\" title=\"caminheiro\" src=\"https:\/\/i0.wp.com\/wpchrisallmeida.s3.amazonaws.com\/wp-content\/uploads\/2011\/08\/caminheiro-150x150.jpg?resize=150%2C150&#038;ssl=1\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do <a title=\"7 de Setembro - Independencia Financeira\" href=\"https:\/\/chrisallmeida.com\/blog\/2011\/07\/projeto-7-de-setembro-independencia-financeira\/\">Projeto 7 de Setembro &#8211; Independ\u00eancia Financeira<\/a>. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja.<br \/>\nHoje quero deixar claro que <strong>apenas boa vontade n\u00e3o \u00e9 suficiente<\/strong>.\u00a0Para adquirir independ\u00eancia financeira e alcan\u00e7ar a prosperidade, alguns passos iniciais s\u00e3o necess\u00e1rios. Este \u00e9 o momento de definir o que voc\u00ea quer de sua vida, arrega\u00e7as as mangas e come\u00e7ar a agir pr\u00e1 valer.<br \/>\nAcredite: Voc\u00ea tamb\u00e9m pode alcan\u00e7ar a sua Independ\u00eancia Financeira e num tempo muito menor do que julgava ser poss\u00edvel. Voc\u00ea merece conquistar isto.<br \/>\nAssista este v\u00eddeo e veja como come\u00e7ar. <!--more-->E depois de assistir, clique nos bot\u00f5es das redes sociais para compartilhar esta postagem com seus amigos.<br \/>\n<object width=\"560\" height=\"349\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/UwS4acLqthY?version=3&amp;hl=pt_BR&amp;rel=0\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><\/object><br \/>\nEstou contigo nesta jornada. Vamos juntos conquistar este novo momento de sua vida.<br \/>\nSucesso e Felicidade Para Voc\u00ea!<br \/>\n<a href=\"https:\/\/i0.wp.com\/wpchrisallmeida.s3.amazonaws.com\/wp-content\/uploads\/2011\/05\/assinatura-chrisallmeida-300.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-306\" title=\"assinatura-chrisallmeida-300\" src=\"https:\/\/i0.wp.com\/wpchrisallmeida.s3.amazonaws.com\/wp-content\/uploads\/2011\/05\/assinatura-chrisallmeida-300.jpg?resize=300%2C59&#038;ssl=1\" alt=\"\" width=\"300\" height=\"59\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro &#8211; Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[21],"tags":[656,1029],"class_list":["post-5536","post","type-post","status-publish","format-standard","hentry","category-independencia-financeira","tag-independencia-financeira-2","tag-prosperidade"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Chris Allmeida\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Prosperidade \u2013 Por onde come\u00e7ar? - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta property=\"og:description\" content=\"Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-08-14T08:00:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-08-14T08:00:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/chrisallmeida\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@chrisallmeida\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Prosperidade \u2013 Por onde come\u00e7ar? - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@chrisallmeida\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#blogposting\",\"name\":\"Prosperidade \\u2013 Por onde come\\u00e7ar? - CHRIS ALLMEIDA BLOG\",\"headline\":\"Prosperidade &#8211; Por onde come\\u00e7ar?\",\"author\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/wpchrisallmeida.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/caminheiro-150x150.jpg\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#articleImage\"},\"datePublished\":\"2011-08-14T05:00:37-03:00\",\"dateModified\":\"2011-08-14T05:00:37-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#webpage\"},\"articleSection\":\"Independencia Financeira, independ\\u00eancia financeira, prosperidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/independencia-financeira\\\/#listItem\",\"name\":\"Independencia Financeira\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/independencia-financeira\\\/#listItem\",\"position\":2,\"name\":\"Independencia Financeira\",\"item\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/independencia-financeira\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#listItem\",\"name\":\"Prosperidade &#8211; Por onde come\\u00e7ar?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#listItem\",\"position\":3,\"name\":\"Prosperidade &#8211; Por onde come\\u00e7ar?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/independencia-financeira\\\/#listItem\",\"name\":\"Independencia Financeira\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\",\"name\":\"Chris Allmeida\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Chris Allmeida\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/chrisallmeida\",\"https:\\\/\\\/twitter.com\\\/chrisallmeida\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/\",\"name\":\"Chris Allmeida\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Chris Allmeida\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#webpage\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/\",\"name\":\"Prosperidade \\u2013 Por onde come\\u00e7ar? - CHRIS ALLMEIDA BLOG\",\"description\":\"Nossa jornada continua. Estamos atravessando este per\\u00edodo preparat\\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\\u00eancia Financeira. Este ser\\u00e1 um trabalho incr\\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\\u00ea precisa saber para alcan\\u00e7ar um grande sucesso no seu neg\\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2011\\\/08\\\/prosperidade-por-onde-comecar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"datePublished\":\"2011-08-14T05:00:37-03:00\",\"dateModified\":\"2011-08-14T05:00:37-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/\",\"name\":\"Chris Allmeida\",\"description\":\"Sucesso e Felicidade para Voc\\u00ea!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Prosperidade \u2013 Por onde come\u00e7ar? - CHRIS ALLMEIDA BLOG","description":"Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar","canonical_url":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#blogposting","name":"Prosperidade \u2013 Por onde come\u00e7ar? - CHRIS ALLMEIDA BLOG","headline":"Prosperidade &#8211; Por onde come\u00e7ar?","author":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"publisher":{"@id":"https:\/\/chrisallmeida.com\/blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/wpchrisallmeida.s3.amazonaws.com\/wp-content\/uploads\/2011\/08\/caminheiro-150x150.jpg","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#articleImage"},"datePublished":"2011-08-14T05:00:37-03:00","dateModified":"2011-08-14T05:00:37-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#webpage"},"isPartOf":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#webpage"},"articleSection":"Independencia Financeira, independ\u00eancia financeira, prosperidade"},{"@type":"BreadcrumbList","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/chrisallmeida.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/independencia-financeira\/#listItem","name":"Independencia Financeira"}},{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/independencia-financeira\/#listItem","position":2,"name":"Independencia Financeira","item":"https:\/\/chrisallmeida.com\/blog\/collections\/independencia-financeira\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#listItem","name":"Prosperidade &#8211; Por onde come\u00e7ar?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#listItem","position":3,"name":"Prosperidade &#8211; Por onde come\u00e7ar?","previousItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/independencia-financeira\/#listItem","name":"Independencia Financeira"}}]},{"@type":"Person","@id":"https:\/\/chrisallmeida.com\/blog\/#person","name":"Chris Allmeida","image":{"@type":"ImageObject","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g","width":96,"height":96,"caption":"Chris Allmeida"},"sameAs":["https:\/\/facebook.com\/chrisallmeida","https:\/\/twitter.com\/chrisallmeida"]},{"@type":"Person","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author","url":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/","name":"Chris Allmeida","image":{"@type":"ImageObject","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","width":96,"height":96,"caption":"Chris Allmeida"}},{"@type":"WebPage","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#webpage","url":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/","name":"Prosperidade \u2013 Por onde come\u00e7ar? - CHRIS ALLMEIDA BLOG","description":"Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/chrisallmeida.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/#breadcrumblist"},"author":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"creator":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"datePublished":"2011-08-14T05:00:37-03:00","dateModified":"2011-08-14T05:00:37-03:00"},{"@type":"WebSite","@id":"https:\/\/chrisallmeida.com\/blog\/#website","url":"https:\/\/chrisallmeida.com\/blog\/","name":"Chris Allmeida","description":"Sucesso e Felicidade para Voc\u00ea!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/chrisallmeida.com\/blog\/#person"}}]},"og:locale":"pt_BR","og:site_name":"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!","og:type":"article","og:title":"Prosperidade \u2013 Por onde come\u00e7ar? - CHRIS ALLMEIDA BLOG","og:description":"Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar","og:url":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/","article:published_time":"2011-08-14T08:00:37+00:00","article:modified_time":"2011-08-14T08:00:37+00:00","article:publisher":"https:\/\/facebook.com\/chrisallmeida","twitter:card":"summary","twitter:site":"@chrisallmeida","twitter:title":"Prosperidade \u2013 Por onde come\u00e7ar? - CHRIS ALLMEIDA BLOG","twitter:description":"Nossa jornada continua. Estamos atravessando este per\u00edodo preparat\u00f3rio para a chegada do Projeto 7 de Setembro - Independ\u00eancia Financeira. Este ser\u00e1 um trabalho incr\u00edvel onde eu transmitirei para os participantes tudo aquilo que voc\u00ea precisa saber para alcan\u00e7ar um grande sucesso no seu neg\u00f3cio, independente de qual ramo ou segmento ele seja. Hoje quero deixar","twitter:creator":"@chrisallmeida"},"aioseo_meta_data":{"post_id":"5536","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-25 22:20:14","updated":"2025-06-14 21:32:35","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chrisallmeida.com\/blog\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chrisallmeida.com\/blog\/collections\/independencia-financeira\/\" title=\"Independencia Financeira\">Independencia Financeira<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProsperidade \u2013 Por onde come\u00e7ar?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/chrisallmeida.com\/blog"},{"label":"Independencia Financeira","link":"https:\/\/chrisallmeida.com\/blog\/collections\/independencia-financeira\/"},{"label":"Prosperidade &#8211; Por onde come\u00e7ar?","link":"https:\/\/chrisallmeida.com\/blog\/blog\/2011\/08\/prosperidade-por-onde-comecar\/"}],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts\/5536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/comments?post=5536"}],"version-history":[{"count":0,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts\/5536\/revisions"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/media?parent=5536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/categories?post=5536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/tags?post=5536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}