{"id":2972,"date":"2013-01-24T07:00:45","date_gmt":"2013-01-24T10:00:45","guid":{"rendered":"https:\/\/chrisallmeida.com\/blog\/?p=2972"},"modified":"2013-01-24T07:00:45","modified_gmt":"2013-01-24T10:00:45","slug":"como-se-tornar-um-pensador-positivo-parte-i","status":"publish","type":"post","link":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/","title":{"rendered":"Como se tornar um pensador positivo &#8211; Parte I"},"content":{"rendered":"<p><a href=\"https:\/\/chrisallmeida.com\/blog\/?attachment_id=2974\" rel=\"attachment wp-att-2974\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-2974\" alt=\"pensamentos-negativos\" src=\"https:\/\/i0.wp.com\/chrisallmeida.com\/blog\/wp-content\/uploads\/2013\/01\/pensamentos-negativos.jpg?resize=340%2C195&#038;ssl=1\" width=\"340\" height=\"195\" \/><\/a>Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito, voc\u00ea pode se surpreender ao saber que ele tamb\u00e9m pode ser bom para sua sa\u00fade. Ent\u00e3o, o que voc\u00ea pode fazer para eliminar os pensamentos negativos e substitu\u00ed-los com uma vis\u00e3o mais positiva? Mesmo se voc\u00ea n\u00e3o \u00e9 um otimista nato, existem coisas que voc\u00ea pode fazer para desenvolver suas habilidades de pensamento positivo e colher alguns benef\u00edcios. Concentre-se em seus pensamentos Para ser um pensador positivo, voc\u00ea precisa aprender a realmente analisar seus pensamentos. Quando voc\u00ea encontrar uma situa\u00e7\u00e3o desafiadora, tente perceber como voc\u00ea pensa sobre o que est\u00e1 acontecendo. Voc\u00ea se envolve em pensamentos negativos? Voc\u00ea mentalmente critica-se ou os outros? Este pensamento negativo apresenta um grande obst\u00e1culo, mas a identifica\u00e7\u00e3o de tais pensamentos \u00e9 o primeiro passo para super\u00e1-los. Alguns dos tipos mais comuns de pensamento negativo envolvem os aspectos indesej\u00e1veis de uma situa\u00e7\u00e3o. Por exemplo, vamos imaginar que voc\u00ea tenha acabado de passar um dia de trabalho. Voc\u00ea fez uma apresenta\u00e7\u00e3o e completou diversas tarefas antes do previsto, mas voc\u00ea esqueceu de devolver um telefonema importante. Apesar do sucesso do dia, \u00e0 noite voc\u00ea se encontra ruminando que um deslize vai afetar o seu sucesso no trabalho. Em vez de refletir sobre o positivo e reconhecendo o negativo, voc\u00ea est\u00e1 ignorando o bom e ampliando o ruim. Auto-culpa \u00e9 outro tipo comum de pensamento negativo. Ap\u00f3s seu departamento n\u00e3o atingido as metas de vendas do m\u00eas, voc\u00ea se culpa ao inv\u00e9s de reconhecer que a economia lenta levou a n\u00e3o atingir as metas. Este tipo de pensamento negativo pode ser particularmente prejudicial para o seu bem-estar psicol\u00f3gico. Ao tomar a culpa por coisas que n\u00e3o s\u00e3o sua culpa ou n\u00e3o est\u00e3o sob seu controle, a sua autoestima e autoconfian\u00e7a tomam uma batida grave.<br \/>\n<a href=\"https:\/\/chrisallmeida.com\/lojavirtual\/material.php?produto=96&amp;nr=1\">Clique aqui e desenvolva a sua \u00a0Autoconfian\u00e7a<\/a><br \/>\nSucesso e Felicidade Para Voc\u00ea!<br \/>\n<a href=\"https:\/\/chrisallmeida.com\/blog\/2013\/01\/apresentacao-sobre-a-unidarma-05012013\/assinatura-chris\/\" rel=\"attachment wp-att-2914\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2914\" alt=\"assinatura-chris\" src=\"https:\/\/i0.wp.com\/chrisallmeida.com\/blog\/wp-content\/uploads\/2013\/01\/assinatura-chris.png?resize=300%2C59&#038;ssl=1\" width=\"300\" height=\"59\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[6],"tags":[190,940],"class_list":["post-2972","post","type-post","status-publish","format-standard","hentry","category-autoconhecimento","tag-autoestima","tag-pensamentos-negativos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Chris Allmeida\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Como se tornar um pensador positivo \u2013 Parte I - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta property=\"og:description\" content=\"Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-01-24T10:00:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-01-24T10:00:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/chrisallmeida\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@chrisallmeida\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Como se tornar um pensador positivo \u2013 Parte I - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@chrisallmeida\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#blogposting\",\"name\":\"Como se tornar um pensador positivo \\u2013 Parte I - CHRIS ALLMEIDA BLOG\",\"headline\":\"Como se tornar um pensador positivo &#8211; Parte I\",\"author\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/pensamentos-negativos.jpg\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#articleImage\"},\"datePublished\":\"2013-01-24T07:00:45-02:00\",\"dateModified\":\"2013-01-24T07:00:45-02:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#webpage\"},\"articleSection\":\"Autoconhecimento, autoestima, pensamentos negativos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/#listItem\",\"name\":\"Autoconhecimento\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/#listItem\",\"position\":2,\"name\":\"Autoconhecimento\",\"item\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#listItem\",\"name\":\"Como se tornar um pensador positivo &#8211; Parte I\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#listItem\",\"position\":3,\"name\":\"Como se tornar um pensador positivo &#8211; Parte I\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/#listItem\",\"name\":\"Autoconhecimento\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\",\"name\":\"Chris Allmeida\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Chris Allmeida\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/chrisallmeida\",\"https:\\\/\\\/twitter.com\\\/chrisallmeida\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/\",\"name\":\"Chris Allmeida\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Chris Allmeida\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#webpage\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/\",\"name\":\"Como se tornar um pensador positivo \\u2013 Parte I - CHRIS ALLMEIDA BLOG\",\"description\":\"Durante um dia agitado, pode tornar-se muito f\\u00e1cil de se concentrar no negativo. Voc\\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\\u00ea saber que o pensamento positivo \\u00e9 melhor para o seu estado de esp\\u00edrito,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2013\\\/01\\\/como-se-tornar-um-pensador-positivo-parte-i\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"datePublished\":\"2013-01-24T07:00:45-02:00\",\"dateModified\":\"2013-01-24T07:00:45-02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/\",\"name\":\"Chris Allmeida\",\"description\":\"Sucesso e Felicidade para Voc\\u00ea!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Como se tornar um pensador positivo \u2013 Parte I - CHRIS ALLMEIDA BLOG","description":"Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito,","canonical_url":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#blogposting","name":"Como se tornar um pensador positivo \u2013 Parte I - CHRIS ALLMEIDA BLOG","headline":"Como se tornar um pensador positivo &#8211; Parte I","author":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"publisher":{"@id":"https:\/\/chrisallmeida.com\/blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/chrisallmeida.com\/blog\/wp-content\/uploads\/2013\/01\/pensamentos-negativos.jpg","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#articleImage"},"datePublished":"2013-01-24T07:00:45-02:00","dateModified":"2013-01-24T07:00:45-02:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#webpage"},"isPartOf":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#webpage"},"articleSection":"Autoconhecimento, autoestima, pensamentos negativos"},{"@type":"BreadcrumbList","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/chrisallmeida.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/#listItem","name":"Autoconhecimento"}},{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/#listItem","position":2,"name":"Autoconhecimento","item":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#listItem","name":"Como se tornar um pensador positivo &#8211; Parte I"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#listItem","position":3,"name":"Como se tornar um pensador positivo &#8211; Parte I","previousItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/#listItem","name":"Autoconhecimento"}}]},{"@type":"Person","@id":"https:\/\/chrisallmeida.com\/blog\/#person","name":"Chris Allmeida","image":{"@type":"ImageObject","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g","width":96,"height":96,"caption":"Chris Allmeida"},"sameAs":["https:\/\/facebook.com\/chrisallmeida","https:\/\/twitter.com\/chrisallmeida"]},{"@type":"Person","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author","url":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/","name":"Chris Allmeida","image":{"@type":"ImageObject","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","width":96,"height":96,"caption":"Chris Allmeida"}},{"@type":"WebPage","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#webpage","url":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/","name":"Como se tornar um pensador positivo \u2013 Parte I - CHRIS ALLMEIDA BLOG","description":"Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/chrisallmeida.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/#breadcrumblist"},"author":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"creator":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"datePublished":"2013-01-24T07:00:45-02:00","dateModified":"2013-01-24T07:00:45-02:00"},{"@type":"WebSite","@id":"https:\/\/chrisallmeida.com\/blog\/#website","url":"https:\/\/chrisallmeida.com\/blog\/","name":"Chris Allmeida","description":"Sucesso e Felicidade para Voc\u00ea!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/chrisallmeida.com\/blog\/#person"}}]},"og:locale":"pt_BR","og:site_name":"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!","og:type":"article","og:title":"Como se tornar um pensador positivo \u2013 Parte I - CHRIS ALLMEIDA BLOG","og:description":"Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito,","og:url":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/","article:published_time":"2013-01-24T10:00:45+00:00","article:modified_time":"2013-01-24T10:00:45+00:00","article:publisher":"https:\/\/facebook.com\/chrisallmeida","twitter:card":"summary","twitter:site":"@chrisallmeida","twitter:title":"Como se tornar um pensador positivo \u2013 Parte I - CHRIS ALLMEIDA BLOG","twitter:description":"Durante um dia agitado, pode tornar-se muito f\u00e1cil de se concentrar no negativo. Voc\u00ea pode se sentir cansado, sobrecarregado e estressado por todas as demandas conflitantes sobre o seu tempo. Como resultado, os pensamentos negativos podem rastejar em sua mente. Enquanto voc\u00ea saber que o pensamento positivo \u00e9 melhor para o seu estado de esp\u00edrito,","twitter:creator":"@chrisallmeida"},"aioseo_meta_data":{"post_id":"2972","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-25 23:00:07","updated":"2025-06-14 22:24:37","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chrisallmeida.com\/blog\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/\" title=\"Autoconhecimento\">Autoconhecimento<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tComo se tornar um pensador positivo \u2013 Parte I\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/chrisallmeida.com\/blog"},{"label":"Autoconhecimento","link":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/"},{"label":"Como se tornar um pensador positivo &#8211; Parte I","link":"https:\/\/chrisallmeida.com\/blog\/blog\/2013\/01\/como-se-tornar-um-pensador-positivo-parte-i\/"}],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts\/2972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/comments?post=2972"}],"version-history":[{"count":0,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts\/2972\/revisions"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/media?parent=2972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/categories?post=2972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/tags?post=2972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}