{"id":2756,"date":"2012-12-03T11:44:21","date_gmt":"2012-12-03T14:44:21","guid":{"rendered":"https:\/\/chrisallmeida.com\/blog\/?p=2756"},"modified":"2012-12-03T11:44:21","modified_gmt":"2012-12-03T14:44:21","slug":"como-aumentar-sua-autoconfianca","status":"publish","type":"post","link":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/","title":{"rendered":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos"},"content":{"rendered":"<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-2757\" title=\"autoconfianca\" src=\"https:\/\/i0.wp.com\/chrisallmeida.com\/blog\/wp-content\/uploads\/2012\/12\/autoconfianca.jpg?resize=135%2C168&#038;ssl=1\" alt=\"\" width=\"135\" height=\"168\" \/>Recentemente um colega de Internet me escreveu pedindo algumas dicas para <a title=\"Auto Confianca\" href=\"https:\/\/chrisallmeida.com\/link\/autoconfianca.php\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"text-decoration: underline;\">aumentar a autoconfian\u00e7a<\/span><\/strong><\/a>. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem.<\/p>\n<p style=\"text-align: justify;\">Observe dentro de voc\u00ea mesmo:<\/p>\n<p style=\"text-align: justify;\">a) O que sua mente (seus pensamentos) dizem a seu pr\u00f3prio respeito?<\/p>\n<p style=\"text-align: justify;\">b) Voc\u00ea se sente desconfort\u00e1vel ou envergonhado com alguma parte de seu corpo ou com algum aspecto da sua personalidade?\u00a0 (pode ser qualquer coisa, desde uma simples acne, ou arrependimento de a\u00e7\u00f5es do passado ou alguma experi\u00eancia traum\u00e1tica e negativa)<\/p>\n<p style=\"text-align: justify;\">Como se diz aqui na minha terra, \u201cd\u00ea nome aos bois\u201d. O primeiro passo \u00e9 reconhecer tudo o que faz voc\u00ea se sentir indigno, envergonhado ou inferiorado. Identifique estes \u201cfantasmas\u201d dentro de voc\u00ea mesmo, d\u00ea um nome a eles. Se quiser levar o exerc\u00edcio a s\u00e9rio, escreva sobre tudo isto num papel. Depois voc\u00ea pode rasgar ou queimar este papel&#8230; Mas num primeiro momento, tenha a coragem de encarar de frente quais s\u00e3o seus medos.<\/p>\n<p style=\"text-align: justify;\">Ent\u00e3o (uma vez que voc\u00ea identificou qual \u00e9 o seu ponto de inseguran\u00e7a), busque algu\u00e9m para compartilhar sobre isto. Talvez um amigo de confian\u00e7a, um parente&#8230; Enfim, algu\u00e9m que voc\u00ea possa se abrir sem sentir que ser\u00e1 julgado ou condenado. Diga para esta pessoa que voc\u00ea quer apenas desabafar, falar algo a respeito e que n\u00e3o est\u00e1 interessado em conselhos, nem em ser consolado. Diga que quer apenas compartilhar algo que o incomoda.<\/p>\n<p style=\"text-align: justify;\">Lembre-se: Sua autoconfian\u00e7a n\u00e3o vai surgir como m\u00e1gica. N\u00e3o h\u00e1 nenhuma solu\u00e7\u00e3o r\u00e1pida. V\u00e1 expondo ao seu colega os fatores que geram inseguran\u00e7a em sua vida e procure ir buscando, na medida em que se exp\u00f5e, as ra\u00edzes do seu problema. Concentre-se em entender qual \u00e9, afinal, o medo interno que tanto lhe aflige. Verifique se \u00e9 uma emo\u00e7\u00e3o antiga e se este temor \u00e9 realmente relevante ou ainda aplic\u00e1vel em sua vida hoje.<\/p>\n<p style=\"text-align: justify;\">E isso n\u00e3o significa que voc\u00ea tenha que se livrar de tudo aquilo que faz com que voc\u00ea se sinta mal (muitas vezes, voc\u00ea simplesmente n\u00e3o pode!). Voc\u00ea precisa aprender a aceitar a si mesmo, seu passado, suas circunst\u00e2ncias como elas s\u00e3o, sem necessariamente pensar neles como &#8220;ruins&#8221;.<\/p>\n<p style=\"text-align: justify;\">Ao final de tudo, agrade\u00e7a ao seu amigo pela possibilidade de partilhar seus medos. E, em seguida, siga em frente sua vida. De alguma forma, voc\u00ea perceber\u00e1 que isto tudo foi muito \u201cterap\u00eautico\u201d para si. Quem sabe at\u00e9 descubra que n\u00e3o h\u00e1 mais motivos para sentir-se inseguro com aquele ponto que tanto o assombrava.<\/p>\n<p style=\"text-align: justify;\">Se precisar de um \u201cempurr\u00e3ozinho\u201d adicional, recomendo a <a title=\"Auto Confianca\" href=\"https:\/\/chrisallmeida.com\/link\/autoconfianca.php\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"text-decoration: underline;\">reprograma\u00e7\u00e3o mental \u201cDesenvolvendo a Autoconfian\u00e7a\u201d<\/span><\/strong><\/a>. Trata-se de um programa de \u00e1udio-hipnose que atuar\u00e1 no fortalecimento de seus pensamentos. Ouvindo periodicamente esta reprograma\u00e7\u00e3o mental voc\u00ea se sentir\u00e1 mais seguro, autoconfiante e de bem com a vida.<\/p>\n<p style=\"text-align: justify;\"><a title=\"Auto Confianca\" href=\"https:\/\/chrisallmeida.com\/link\/autoconfianca.php\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"text-decoration: underline;\">Clique aqui para acessar agora mesma esta Reprograma\u00e7\u00e3o.<\/span><\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Sucesso e Felicidade Para Voc\u00ea!<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/wpchrisallmeida.s3.amazonaws.com\/wp-content\/uploads\/2011\/05\/assinatura-chrisallmeida-300.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-306\" title=\"Assinatura Chris Allmeida Poder Pessoal e Autoconhecimento\" src=\"https:\/\/i0.wp.com\/wpchrisallmeida.s3.amazonaws.com\/wp-content\/uploads\/2011\/05\/assinatura-chrisallmeida-300.jpg?resize=300%2C59&#038;ssl=1\" alt=\"Assinatura Chris Allmeida Poder Pessoal e Autoconhecimento\" width=\"300\" height=\"59\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[6,42],"tags":[294,420],"class_list":["post-2756","post","type-post","status-publish","format-standard","hentry","category-autoconhecimento","category-reprogramacao-mental","tag-como-aumentar-sua-autoconfianca","tag-desenvolvendo-a-autoconfianca"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Chris Allmeida\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta property=\"og:description\" content=\"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-12-03T14:44:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-12-03T14:44:21+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/chrisallmeida\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@chrisallmeida\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a)\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@chrisallmeida\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#blogposting\",\"name\":\"Como aumentar sua autoconfian\\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG\",\"headline\":\"Como aumentar sua autoconfian\\u00e7a e livrar-se de antigos medos\",\"author\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/autoconfianca.jpg\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#articleImage\"},\"datePublished\":\"2012-12-03T11:44:21-02:00\",\"dateModified\":\"2012-12-03T11:44:21-02:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#webpage\"},\"articleSection\":\"Autoconhecimento, Reprograma\\u00e7\\u00e3o Mental, Como aumentar sua autoconfian\\u00e7a, Desenvolvendo a Autoconfian\\u00e7a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/#listItem\",\"name\":\"Autoconhecimento\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/#listItem\",\"position\":2,\"name\":\"Autoconhecimento\",\"item\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#listItem\",\"name\":\"Como aumentar sua autoconfian\\u00e7a e livrar-se de antigos medos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#listItem\",\"position\":3,\"name\":\"Como aumentar sua autoconfian\\u00e7a e livrar-se de antigos medos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/collections\\\/autoconhecimento\\\/#listItem\",\"name\":\"Autoconhecimento\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\",\"name\":\"Chris Allmeida\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Chris Allmeida\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/chrisallmeida\",\"https:\\\/\\\/twitter.com\\\/chrisallmeida\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/\",\"name\":\"Chris Allmeida\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Chris Allmeida\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#webpage\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/\",\"name\":\"Como aumentar sua autoconfian\\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG\",\"description\":\"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\\u00e7a. Bom, a falta de autoconfian\\u00e7a est\\u00e1 sempre relacionada a algum ponto na sua vida onde voc\\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\\u00f3prias inseguran\\u00e7as e reconhecer que elas existem. Observe dentro de voc\\u00ea mesmo: a)\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/2012\\\/12\\\/como-aumentar-sua-autoconfianca\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/blog\\\/author\\\/user\\\/#author\"},\"datePublished\":\"2012-12-03T11:44:21-02:00\",\"dateModified\":\"2012-12-03T11:44:21-02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/\",\"name\":\"Chris Allmeida\",\"description\":\"Sucesso e Felicidade para Voc\\u00ea!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG","description":"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a)","canonical_url":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#blogposting","name":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG","headline":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos","author":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"publisher":{"@id":"https:\/\/chrisallmeida.com\/blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/chrisallmeida.com\/blog\/wp-content\/uploads\/2012\/12\/autoconfianca.jpg","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#articleImage"},"datePublished":"2012-12-03T11:44:21-02:00","dateModified":"2012-12-03T11:44:21-02:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#webpage"},"isPartOf":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#webpage"},"articleSection":"Autoconhecimento, Reprograma\u00e7\u00e3o Mental, Como aumentar sua autoconfian\u00e7a, Desenvolvendo a Autoconfian\u00e7a"},{"@type":"BreadcrumbList","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/chrisallmeida.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/#listItem","name":"Autoconhecimento"}},{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/#listItem","position":2,"name":"Autoconhecimento","item":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#listItem","name":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#listItem","position":3,"name":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos","previousItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/#listItem","name":"Autoconhecimento"}}]},{"@type":"Person","@id":"https:\/\/chrisallmeida.com\/blog\/#person","name":"Chris Allmeida","image":{"@type":"ImageObject","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g","width":96,"height":96,"caption":"Chris Allmeida"},"sameAs":["https:\/\/facebook.com\/chrisallmeida","https:\/\/twitter.com\/chrisallmeida"]},{"@type":"Person","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author","url":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/","name":"Chris Allmeida","image":{"@type":"ImageObject","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","width":96,"height":96,"caption":"Chris Allmeida"}},{"@type":"WebPage","@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#webpage","url":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/","name":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG","description":"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a)","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/chrisallmeida.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/#breadcrumblist"},"author":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"creator":{"@id":"https:\/\/chrisallmeida.com\/blog\/blog\/author\/user\/#author"},"datePublished":"2012-12-03T11:44:21-02:00","dateModified":"2012-12-03T11:44:21-02:00"},{"@type":"WebSite","@id":"https:\/\/chrisallmeida.com\/blog\/#website","url":"https:\/\/chrisallmeida.com\/blog\/","name":"Chris Allmeida","description":"Sucesso e Felicidade para Voc\u00ea!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/chrisallmeida.com\/blog\/#person"}}]},"og:locale":"pt_BR","og:site_name":"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!","og:type":"article","og:title":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG","og:description":"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a)","og:url":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/","article:published_time":"2012-12-03T14:44:21+00:00","article:modified_time":"2012-12-03T14:44:21+00:00","article:publisher":"https:\/\/facebook.com\/chrisallmeida","twitter:card":"summary","twitter:site":"@chrisallmeida","twitter:title":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos - CHRIS ALLMEIDA BLOG","twitter:description":"Recentemente um colega de Internet me escreveu pedindo algumas dicas para aumentar a autoconfian\u00e7a. Bom, a falta de autoconfian\u00e7a est\u00e1 sempre relacionada a algum ponto na sua vida onde voc\u00ea se sente inseguro. E, neste caso, o primeiro passo para vencer suas pr\u00f3prias inseguran\u00e7as e reconhecer que elas existem. Observe dentro de voc\u00ea mesmo: a)","twitter:creator":"@chrisallmeida"},"aioseo_meta_data":{"post_id":"2756","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-25 22:54:17","updated":"2025-06-14 22:17:35","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chrisallmeida.com\/blog\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/\" title=\"Autoconhecimento\">Autoconhecimento<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tComo aumentar sua autoconfian\u00e7a e livrar-se de antigos medos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/chrisallmeida.com\/blog"},{"label":"Autoconhecimento","link":"https:\/\/chrisallmeida.com\/blog\/collections\/autoconhecimento\/"},{"label":"Como aumentar sua autoconfian\u00e7a e livrar-se de antigos medos","link":"https:\/\/chrisallmeida.com\/blog\/blog\/2012\/12\/como-aumentar-sua-autoconfianca\/"}],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts\/2756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/comments?post=2756"}],"version-history":[{"count":0,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/posts\/2756\/revisions"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/media?parent=2756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/categories?post=2756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/tags?post=2756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}