{"id":5469,"date":"2011-06-25T15:32:32","date_gmt":"2011-06-25T18:32:32","guid":{"rendered":"https:\/\/chrisallmeida.com\/blog\/?page_id=382"},"modified":"2011-06-25T15:32:32","modified_gmt":"2011-06-25T18:32:32","slug":"unidarma","status":"publish","type":"page","link":"https:\/\/chrisallmeida.com\/blog\/unidarma\/","title":{"rendered":"Unidarma"},"content":{"rendered":"<p style=\"text-align: center;\"><object width=\"460\" height=\"358\" type=\"application\/x-shockwave-flash\" data=\"http:\/\/flv-player.net\/medias\/player_flv_maxi.swf\"><param name=\"movie\" value=\"http:\/\/flv-player.net\/medias\/player_flv_maxi.swf\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"FlashVars\" value=\"flv=http%3A\/\/chrisallmeida.com\/unidarmamultinivel\/video\/video2cursos.flv&amp;title=CLIQUE    AQUI!&amp;showstop=1&amp;showvolume=1&amp;showtime=1&amp;showfullscreen=1&amp;showiconplay=1\" \/><\/object><\/p>\n<p>A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal.<br \/>\nPor um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas).<br \/>\nAl\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas ministradas AO VIVO, durante a vig\u00eancia de sua assinatura. Oferecemos, pelo menos, duas novas aulas ao vivo toda semana com diferentes temas voltados para seu aprimoramento!<br \/>\nAl\u00e9m disso, sendo assinante da Unidarma voc\u00ea autmaticamente come\u00e7a a fazer parte do nosso plano de Ganhos.<br \/>\n<a title=\"Benef\u00edcios da Unidarma\" href=\"https:\/\/chrisallmeida.com\/blog\/2011\/07\/beneficios-da-unidarma\/\">Saiba mais sobre os benef\u00edcios da Unidarma<\/a><br \/>\nPara efetuar sua matr\u00edcula, acesse o <a title=\"Unidarma Desenvolvimento Pessoal\" href=\"http:\/\/unidarma.org\/ca\" target=\"_blank\" rel=\"noopener\">site oficial da Unidarma<\/a>.<br \/>\n<a href=\"http:\/\/unidarma.org\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Unidarma\" src=\"https:\/\/i0.wp.com\/chrisallmeida.com\/unidarma\/logo-unidarma-500.jpg?resize=499%2C133&#038;ssl=1\" alt=\"\" width=\"499\" height=\"133\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-5469","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/chrisallmeida.com\/blog\/unidarma\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Unidarma - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta property=\"og:description\" content=\"A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chrisallmeida.com\/blog\/unidarma\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-06-25T18:32:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-06-25T18:32:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/chrisallmeida\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@chrisallmeida\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Unidarma - CHRIS ALLMEIDA BLOG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@chrisallmeida\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/unidarma\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/unidarma\\\/#listItem\",\"name\":\"Unidarma\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/unidarma\\\/#listItem\",\"position\":2,\"name\":\"Unidarma\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog#listItem\",\"name\":\"In\\u00edcio\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\",\"name\":\"Chris Allmeida\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/unidarma\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Chris Allmeida\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/chrisallmeida\",\"https:\\\/\\\/twitter.com\\\/chrisallmeida\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/unidarma\\\/#webpage\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/unidarma\\\/\",\"name\":\"Unidarma - CHRIS ALLMEIDA BLOG\",\"description\":\"A Unidarma \\u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\\u00ea efetua sua matr\\u00edcula como aluno-assinante da Unidarma e, ap\\u00f3s confirmarmos seu pagamento, voc\\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\\u00eddeos, \\u00e1udios e apostilas). Al\\u00e9m disso, poder\\u00e1 tamb\\u00e9m participar de todas as aulas\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/unidarma\\\/#breadcrumblist\"},\"datePublished\":\"2011-06-25T15:32:32-03:00\",\"dateModified\":\"2011-06-25T15:32:32-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/\",\"name\":\"Chris Allmeida\",\"description\":\"Sucesso e Felicidade para Voc\\u00ea!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/chrisallmeida.com\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Unidarma - CHRIS ALLMEIDA BLOG","description":"A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas","canonical_url":"https:\/\/chrisallmeida.com\/blog\/unidarma\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/chrisallmeida.com\/blog\/unidarma\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/chrisallmeida.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/unidarma\/#listItem","name":"Unidarma"}},{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog\/unidarma\/#listItem","position":2,"name":"Unidarma","previousItem":{"@type":"ListItem","@id":"https:\/\/chrisallmeida.com\/blog#listItem","name":"In\u00edcio"}}]},{"@type":"Person","@id":"https:\/\/chrisallmeida.com\/blog\/#person","name":"Chris Allmeida","image":{"@type":"ImageObject","@id":"https:\/\/chrisallmeida.com\/blog\/unidarma\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/8a1838a2b4e5884c79c187219182959ce3f99a80f4f141d8d6c2ac896c9b9357?s=96&d=mm&r=g","width":96,"height":96,"caption":"Chris Allmeida"},"sameAs":["https:\/\/facebook.com\/chrisallmeida","https:\/\/twitter.com\/chrisallmeida"]},{"@type":"WebPage","@id":"https:\/\/chrisallmeida.com\/blog\/unidarma\/#webpage","url":"https:\/\/chrisallmeida.com\/blog\/unidarma\/","name":"Unidarma - CHRIS ALLMEIDA BLOG","description":"A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/chrisallmeida.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/chrisallmeida.com\/blog\/unidarma\/#breadcrumblist"},"datePublished":"2011-06-25T15:32:32-03:00","dateModified":"2011-06-25T15:32:32-03:00"},{"@type":"WebSite","@id":"https:\/\/chrisallmeida.com\/blog\/#website","url":"https:\/\/chrisallmeida.com\/blog\/","name":"Chris Allmeida","description":"Sucesso e Felicidade para Voc\u00ea!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/chrisallmeida.com\/blog\/#person"}}]},"og:locale":"pt_BR","og:site_name":"CHRIS ALLMEIDA BLOG - Sucesso e Felicidade para Voc\u00ea!","og:type":"article","og:title":"Unidarma - CHRIS ALLMEIDA BLOG","og:description":"A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas","og:url":"https:\/\/chrisallmeida.com\/blog\/unidarma\/","article:published_time":"2011-06-25T18:32:32+00:00","article:modified_time":"2011-06-25T18:32:32+00:00","article:publisher":"https:\/\/facebook.com\/chrisallmeida","twitter:card":"summary","twitter:site":"@chrisallmeida","twitter:title":"Unidarma - CHRIS ALLMEIDA BLOG","twitter:description":"A Unidarma \u00e9 uma escola online de Desenvolvimento Pessoal. Por um pequeno investimento mensal, voc\u00ea efetua sua matr\u00edcula como aluno-assinante da Unidarma e, ap\u00f3s confirmarmos seu pagamento, voc\u00ea passa a ter ACESSO TOTAL a todos os nossos cursos (em formato de centenas v\u00eddeos, \u00e1udios e apostilas). Al\u00e9m disso, poder\u00e1 tamb\u00e9m participar de todas as aulas","twitter:creator":"@chrisallmeida"},"aioseo_meta_data":{"post_id":"5469","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-25 21:50:52","updated":"2025-06-14 20:51:20","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chrisallmeida.com\/blog\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUnidarma\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/chrisallmeida.com\/blog"},{"label":"Unidarma","link":"https:\/\/chrisallmeida.com\/blog\/unidarma\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/pages\/5469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/comments?post=5469"}],"version-history":[{"count":0,"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/pages\/5469\/revisions"}],"wp:attachment":[{"href":"https:\/\/chrisallmeida.com\/blog\/wp-json\/wp\/v2\/media?parent=5469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}